﻿{"id":39,"count":68,"description":"","link":"https:\/\/www.sortlist.de\/blog\/category\/business\/sales\/","name":"Sales &amp; Customer Success","slug":"sales","taxonomy":"category","parent":89,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sales &amp; Customer Success Archives - Sortlist Blog<\/title>\n<meta name=\"description\" content=\"Erfolgreicher Verkauf und Kundenbindung: Entdecke in unserer Blog-Kategorie f\u00fcr Sales &amp; Customer Success Experten-Tipps und Strategien f\u00fcr dein Unternehmen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sortlist.de\/blog\/category\/business\/sales\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sales &amp; Customer Success Archives - Sortlist Blog\" \/>\n<meta property=\"og:description\" content=\"Erfolgreicher Verkauf und Kundenbindung: Entdecke in unserer Blog-Kategorie f\u00fcr Sales &amp; Customer Success Experten-Tipps und Strategien f\u00fcr dein Unternehmen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sortlist.de\/blog\/category\/business\/sales\/\" \/>\n<meta property=\"og:site_name\" content=\"Sortlist Blog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.sortlist.de\\\/blog\\\/category\\\/business\\\/sales\\\/\",\"url\":\"https:\\\/\\\/www.sortlist.de\\\/blog\\\/category\\\/business\\\/sales\\\/\",\"name\":\"Sales &amp; Customer Success Archives - Sortlist Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sortlist.de\\\/blog\\\/#website\"},\"description\":\"Erfolgreicher Verkauf und Kundenbindung: Entdecke in unserer Blog-Kategorie f\u00fcr Sales & Customer Success Experten-Tipps und Strategien f\u00fcr dein Unternehmen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sortlist.de\\\/blog\\\/category\\\/business\\\/sales\\\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sortlist.de\\\/blog\\\/category\\\/business\\\/sales\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.sortlist.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Business Insights\",\"item\":\"https:\\\/\\\/www.sortlist.de\\\/blog\\\/category\\\/business\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sales &amp; Customer Success\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sortlist.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.sortlist.de\\\/blog\\\/\",\"name\":\"Sortlist Blog\",\"description\":\"Sortlist Blog\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sortlist.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sales &amp; Customer Success Archives - Sortlist Blog","description":"Erfolgreicher Verkauf und Kundenbindung: Entdecke in unserer Blog-Kategorie f\u00fcr Sales & Customer Success Experten-Tipps und Strategien f\u00fcr dein Unternehmen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sortlist.de\/blog\/category\/business\/sales\/","og_locale":"de_DE","og_type":"article","og_title":"Sales &amp; Customer Success Archives - Sortlist Blog","og_description":"Erfolgreicher Verkauf und Kundenbindung: Entdecke in unserer Blog-Kategorie f\u00fcr Sales & Customer Success Experten-Tipps und Strategien f\u00fcr dein Unternehmen.","og_url":"https:\/\/www.sortlist.de\/blog\/category\/business\/sales\/","og_site_name":"Sortlist Blog","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.sortlist.de\/blog\/category\/business\/sales\/","url":"https:\/\/www.sortlist.de\/blog\/category\/business\/sales\/","name":"Sales &amp; Customer Success Archives - Sortlist Blog","isPartOf":{"@id":"https:\/\/www.sortlist.de\/blog\/#website"},"description":"Erfolgreicher Verkauf und Kundenbindung: Entdecke in unserer Blog-Kategorie f\u00fcr Sales & Customer Success Experten-Tipps und Strategien f\u00fcr dein Unternehmen.","breadcrumb":{"@id":"https:\/\/www.sortlist.de\/blog\/category\/business\/sales\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/www.sortlist.de\/blog\/category\/business\/sales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.sortlist.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Business Insights","item":"https:\/\/www.sortlist.de\/blog\/category\/business\/"},{"@type":"ListItem","position":3,"name":"Sales &amp; Customer Success"}]},{"@type":"WebSite","@id":"https:\/\/www.sortlist.de\/blog\/#website","url":"https:\/\/www.sortlist.de\/blog\/","name":"Sortlist Blog","description":"Sortlist Blog","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sortlist.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.sortlist.de\/blog\/wp-json\/wp\/v2\/categories\/39","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sortlist.de\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.sortlist.de\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/www.sortlist.de\/blog\/wp-json\/wp\/v2\/categories\/89"}],"wp:post_type":[{"href":"https:\/\/www.sortlist.de\/blog\/wp-json\/wp\/v2\/posts?categories=39"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}